{"id":121686,"date":"2022-09-27T11:27:52","date_gmt":"2022-09-27T09:27:52","guid":{"rendered":"https:\/\/www.lifestylehotels.net\/?post_type=stories&#038;p=121686"},"modified":"2022-11-29T09:25:28","modified_gmt":"2022-11-29T08:25:28","slug":"gradonnas-mountain-resort-kals-osterreich-magdalena-s-naturkosmetik-geht-unter-die-haut","status":"publish","type":"stories","link":"https:\/\/www.lifestylehotels.net\/de\/story\/gradonnas-mountain-resort-kals-osterreich-magdalena-s-naturkosmetik-geht-unter-die-haut\/","title":{"rendered":"Gradonna****S Mountain Resort, Kals, \u00d6sterreich: MAGDALENA\u2019S Naturkosmetik geht unter die Haut"},"content":{"rendered":"\n<p style=\"font-size:23px\"><strong>Die Pflegemarke \u201eMAGDALENA\u2019S made in Tyrol\u201c sch\u00f6pft ihre Kraft aus der Natur. Dank veganen und regionalen Inhaltsstoffen begeistern die Produkte nicht nur im Gradonna****S Mountain Resort \u2013 dem Ursprung der Beauty-Marke.<\/strong><\/p>\n\n\n\n<p style=\"font-size:17px\">Eine Kosmetiklinie zu finden, ist einfach \u2013 die richtigen Produkte f\u00fcr nat\u00fcrliche Sch\u00f6nheit hingegen schwer. F\u00fcr Martha Schultz, Mitinhaberin des <a href=\"https:\/\/www.lifestylehotels.net\/de\/hotel\/gradonna-mountain-resort\/\" target=\"_blank\" rel=\"noreferrer noopener\">Gradonna****s Mountain Resort<\/a> in Kals am Gro\u00dfglockner, soll das ideale Konzept f\u00fcr die Haut besonders nachhaltig sein sowie vegane und regionale Inhaltsstoffe vereinen. Im Gespr\u00e4ch mit \u201eThe Stylemate\u201c erz\u00e4hlt sie: \u201eRegionalit\u00e4t und eine ausgezeichnete Qualit\u00e4t der Produkte sind f\u00fcr uns essenziell.\u201c Am Kosmetikmarkt war allerdings kein Partner zu finden, der den hohen Anspr\u00fcchen gen\u00fcgt. Aus diesem Grund entschieden sie sich f\u00fcr die Gr\u00fcndung von MAGDALENA\u2019S.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1040\" height=\"694\" src=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2022\/09\/Story_Magdalenas.png\" alt=\"\" class=\"wp-image-126603\" srcset=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2022\/09\/Story_Magdalenas.png 1040w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2022\/09\/Story_Magdalenas-768x512.png 768w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2022\/09\/Story_Magdalenas-360x240.png 360w\" sizes=\"(max-width: 1040px) 100vw, 1040px\" \/><\/figure>\n\n\n\n<p>Die eigenen Anforderungen an die Pflegeprodukte sind ambitioniert: Hochwertig, regional, tierversuchsfrei, in Bioqualit\u00e4t und vegan \u2013 diese Attribute sind im Vier-Sterne-Superior-Hotel wichtig und auch essenziell f\u00fcr die Beauty-Produkte. \u201eUnsere Kr\u00e4uterexpertinnen schufen gemeinsam mit meinem Sohn Lukas im Jahr 2012 ein innovatives Pflege- und Kosmetikkonzept, das sowohl Frauen als auch M\u00e4nner begeistert\u201c, erz\u00e4hlt Schultz von der Geburtsstunde der Marke.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\"><strong>Vegan, regional und hochwertig<\/strong><\/h3>\n\n\n\n<p>\u00dcber die letzten Jahre wurde die Rezeptur der Produkte perfektioniert und die Herstellung auf die verst\u00e4rkte Nachfrage angepasst: \u201eMAGDALENA\u2019S made in Tyrol\u201c besticht nicht nur durch kurze Lieferwege, die Pflegelinie wird auch komplett von Hand angefertigt. Seit letztem Dezember ist die heimische Kosmetiklinie zertifiziert und tr\u00e4gt ebenso das Bio-Zertifikat. \u201eMAGDALENA\u2018S k\u00fcmmert sich um die Haut ihrer Anwenderinnen und Anwender. Alle Produkte unserer gro\u00dfz\u00fcgigen Palette sind sehr gut vertr\u00e4glich und parfumfrei \u2013 trotzdem duften sie nach \u201aGebirge\u2018 und vermitteln so die Freiheit der Berge\u201c, sagt der Pharmazeut Mag. Lukas Schultz. Zuerst wurde die neue Linie exklusiv im Resort in Kals am Gro\u00dfglockner eingesetzt, \u201edoch aufgrund der gro\u00dfen Nachfrage kann man sie inzwischen auch nach Hause bestellen\u201c, f\u00fcgt Martha Schultz hinzu und verweist auf die Website magdalenas.tirol.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1000\" height=\"1500\" data-id=\"128275\" src=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2022\/09\/17-2-LR_magdalenas_all_gert_perauer.jpg\" alt=\"\" class=\"wp-image-128275\" srcset=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2022\/09\/17-2-LR_magdalenas_all_gert_perauer.jpg 1000w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2022\/09\/17-2-LR_magdalenas_all_gert_perauer-768x1152.jpg 768w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2022\/09\/17-2-LR_magdalenas_all_gert_perauer-360x540.jpg 360w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"1000\" height=\"1500\" data-id=\"128273\" src=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2022\/09\/18-LR_magdalenas_all_gert_perauer.jpg\" alt=\"\" class=\"wp-image-128273\" srcset=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2022\/09\/18-LR_magdalenas_all_gert_perauer.jpg 1000w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2022\/09\/18-LR_magdalenas_all_gert_perauer-768x1152.jpg 768w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2022\/09\/18-LR_magdalenas_all_gert_perauer-360x540.jpg 360w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>Die Pflegeserie ist eine echte Familien-Erfolgsgeschichte. Das beweist auch der Name: Patin f\u00fcr \u201eMAGDALENA\u2019S\u201c ist die Nichte von Martha Schultz. Und was sagen die G\u00e4ste dazu? \u201eDie R\u00fcckmeldungen sind durchwegs positiv. Vor allem der Verw\u00f6hneffekt der Cremen und Lotion sowie der hohe Feuchtigkeitsanteil der Pflege- und Kosmetikprodukte werden immer wieder positiv erw\u00e4hnt. Auch \u00fcber unseren Onlineshop magdalenas.tirol bekommen wir viele begeisterte R\u00fcckmeldungen\u201c, freut sich Martha Schultz. Mit der alpinen Kosmetiklinie aus dem Gradonna****s Mountain Resort kreierten die Profis wohltuende Produkte, die naturbewusste M\u00e4nner und Frauen begeistern.<\/p>\n\n\n\n<p>Magdalena&#8217;s by Gradonna <a href=\"https:\/\/magdalenas.tirol\/\" target=\"_blank\" rel=\"noreferrer noopener\">Onlineshop &gt;&gt; <\/a><\/p>\n\n\n\n<p><strong><a href=\"https:\/\/www.lifestylehotels.net\/de\/hotel\/gradonna-mountain-resort\/\" target=\"_blank\" rel=\"noreferrer noopener\">Gradonna Mountain Resort<\/a> is a Member of <a href=\"https:\/\/www.lifestylehotels.net\/de\/\" target=\"_blank\" rel=\"noreferrer noopener\">Lifestylehotels<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Pflegemarke \u201eMAGDALENA\u2019S made in Tyrol\u201c sch\u00f6pft ihre Kraft aus der Natur. Dank veganen und regionalen Inhaltsstoffen begeistern die Produkte nicht nur im Gradonna****S Mountain Resort \u2013 dem Ursprung der Beauty-Marke &#8230;<\/p>\n","protected":false},"author":4,"featured_media":128271,"template":"","meta":{"inline_featured_image":false},"categories":[2274],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.9.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Magdalena&#039;s Naturkosmetik geht unter die Haut - Lifestylehotels\u2122<\/title>\n<meta name=\"description\" content=\"Die Pflegemarke \u201eMAGDALENA\u2019S\u201c sch\u00f6pft ihre Kraft aus der Natur. Die veganen und regionalen Produkte begeistern die G\u00e4ste im Gradonna****S.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lifestylehotels.net\/de\/story\/gradonnas-mountain-resort-kals-osterreich-magdalena-s-naturkosmetik-geht-unter-die-haut\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Magdalena&#039;s Naturkosmetik geht unter die Haut - Lifestylehotels\u2122\" \/>\n<meta property=\"og:description\" content=\"Die Pflegemarke \u201eMAGDALENA\u2019S\u201c sch\u00f6pft ihre Kraft aus der Natur. Die veganen und regionalen Produkte begeistern die G\u00e4ste im Gradonna****S.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lifestylehotels.net\/de\/story\/gradonnas-mountain-resort-kals-osterreich-magdalena-s-naturkosmetik-geht-unter-die-haut\/\" \/>\n<meta property=\"og:site_name\" content=\"Lifestylehotels\u2122\" \/>\n<meta property=\"article:modified_time\" content=\"2022-11-29T08:25:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2022\/09\/19-4497-web_magdalenas_by_gert_perauer.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2048\" \/>\n\t<meta property=\"og:image:height\" content=\"1365\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lifestylehotels.net\/de\/story\/gradonnas-mountain-resort-kals-osterreich-magdalena-s-naturkosmetik-geht-unter-die-haut\/\",\"url\":\"https:\/\/www.lifestylehotels.net\/de\/story\/gradonnas-mountain-resort-kals-osterreich-magdalena-s-naturkosmetik-geht-unter-die-haut\/\",\"name\":\"Magdalena's Naturkosmetik geht unter die Haut - Lifestylehotels\u2122\",\"isPartOf\":{\"@id\":\"https:\/\/www.lifestylehotels.net\/de\/#website\"},\"datePublished\":\"2022-09-27T09:27:52+00:00\",\"dateModified\":\"2022-11-29T08:25:28+00:00\",\"description\":\"Die Pflegemarke \u201eMAGDALENA\u2019S\u201c sch\u00f6pft ihre Kraft aus der Natur. Die veganen und regionalen Produkte begeistern die G\u00e4ste im Gradonna****S.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lifestylehotels.net\/de\/story\/gradonnas-mountain-resort-kals-osterreich-magdalena-s-naturkosmetik-geht-unter-die-haut\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lifestylehotels.net\/de\/story\/gradonnas-mountain-resort-kals-osterreich-magdalena-s-naturkosmetik-geht-unter-die-haut\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lifestylehotels.net\/de\/story\/gradonnas-mountain-resort-kals-osterreich-magdalena-s-naturkosmetik-geht-unter-die-haut\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.lifestylehotels.net\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Gradonna****S Mountain Resort, Kals, \u00d6sterreich: MAGDALENA\u2019S Naturkosmetik geht unter die Haut\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lifestylehotels.net\/de\/#website\",\"url\":\"https:\/\/www.lifestylehotels.net\/de\/\",\"name\":\"Lifestylehotels\u2122\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lifestylehotels.net\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Magdalena's Naturkosmetik geht unter die Haut - Lifestylehotels\u2122","description":"Die Pflegemarke \u201eMAGDALENA\u2019S\u201c sch\u00f6pft ihre Kraft aus der Natur. Die veganen und regionalen Produkte begeistern die G\u00e4ste im Gradonna****S.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lifestylehotels.net\/de\/story\/gradonnas-mountain-resort-kals-osterreich-magdalena-s-naturkosmetik-geht-unter-die-haut\/","og_locale":"de_DE","og_type":"article","og_title":"Magdalena's Naturkosmetik geht unter die Haut - Lifestylehotels\u2122","og_description":"Die Pflegemarke \u201eMAGDALENA\u2019S\u201c sch\u00f6pft ihre Kraft aus der Natur. Die veganen und regionalen Produkte begeistern die G\u00e4ste im Gradonna****S.","og_url":"https:\/\/www.lifestylehotels.net\/de\/story\/gradonnas-mountain-resort-kals-osterreich-magdalena-s-naturkosmetik-geht-unter-die-haut\/","og_site_name":"Lifestylehotels\u2122","article_modified_time":"2022-11-29T08:25:28+00:00","og_image":[{"width":2048,"height":1365,"url":"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2022\/09\/19-4497-web_magdalenas_by_gert_perauer.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.lifestylehotels.net\/de\/story\/gradonnas-mountain-resort-kals-osterreich-magdalena-s-naturkosmetik-geht-unter-die-haut\/","url":"https:\/\/www.lifestylehotels.net\/de\/story\/gradonnas-mountain-resort-kals-osterreich-magdalena-s-naturkosmetik-geht-unter-die-haut\/","name":"Magdalena's Naturkosmetik geht unter die Haut - Lifestylehotels\u2122","isPartOf":{"@id":"https:\/\/www.lifestylehotels.net\/de\/#website"},"datePublished":"2022-09-27T09:27:52+00:00","dateModified":"2022-11-29T08:25:28+00:00","description":"Die Pflegemarke \u201eMAGDALENA\u2019S\u201c sch\u00f6pft ihre Kraft aus der Natur. Die veganen und regionalen Produkte begeistern die G\u00e4ste im Gradonna****S.","breadcrumb":{"@id":"https:\/\/www.lifestylehotels.net\/de\/story\/gradonnas-mountain-resort-kals-osterreich-magdalena-s-naturkosmetik-geht-unter-die-haut\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lifestylehotels.net\/de\/story\/gradonnas-mountain-resort-kals-osterreich-magdalena-s-naturkosmetik-geht-unter-die-haut\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.lifestylehotels.net\/de\/story\/gradonnas-mountain-resort-kals-osterreich-magdalena-s-naturkosmetik-geht-unter-die-haut\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.lifestylehotels.net\/de\/"},{"@type":"ListItem","position":2,"name":"Gradonna****S Mountain Resort, Kals, \u00d6sterreich: MAGDALENA\u2019S Naturkosmetik geht unter die Haut"}]},{"@type":"WebSite","@id":"https:\/\/www.lifestylehotels.net\/de\/#website","url":"https:\/\/www.lifestylehotels.net\/de\/","name":"Lifestylehotels\u2122","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lifestylehotels.net\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lifestylehotels.net\/de\/wp-json\/wp\/v2\/stories\/121686"}],"collection":[{"href":"https:\/\/www.lifestylehotels.net\/de\/wp-json\/wp\/v2\/stories"}],"about":[{"href":"https:\/\/www.lifestylehotels.net\/de\/wp-json\/wp\/v2\/types\/stories"}],"author":[{"embeddable":true,"href":"https:\/\/www.lifestylehotels.net\/de\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":12,"href":"https:\/\/www.lifestylehotels.net\/de\/wp-json\/wp\/v2\/stories\/121686\/revisions"}],"predecessor-version":[{"id":128278,"href":"https:\/\/www.lifestylehotels.net\/de\/wp-json\/wp\/v2\/stories\/121686\/revisions\/128278"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lifestylehotels.net\/de\/wp-json\/wp\/v2\/media\/128271"}],"wp:attachment":[{"href":"https:\/\/www.lifestylehotels.net\/de\/wp-json\/wp\/v2\/media?parent=121686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lifestylehotels.net\/de\/wp-json\/wp\/v2\/categories?post=121686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lifestylehotels.net\/de\/wp-json\/wp\/v2\/tags?post=121686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}