{"id":43809,"date":"2020-12-30T13:22:01","date_gmt":"2020-12-30T12:22:01","guid":{"rendered":"https:\/\/www.lifestylehotels.net\/?post_type=stories&#038;p=43809"},"modified":"2022-03-10T11:54:42","modified_gmt":"2022-03-10T10:54:42","slug":"sand-timmendorfer-strand-deutschland-entspannung-mit-weitblick","status":"publish","type":"stories","link":"https:\/\/www.lifestylehotels.net\/de\/story\/sand-timmendorfer-strand-deutschland-entspannung-mit-weitblick\/","title":{"rendered":"SAND, Timmendorfer Strand, Deutschland: Entspannung mit Weitblick"},"content":{"rendered":"\n<p style=\"font-size:23px\"><strong>Im <a href=\"https:\/\/www.lifestylehotels.net\/de\/hotel\/sand\/\">SAND<\/a>, das nur einige Gehminuten vom Timmendorfer Strand entfernt liegt, genie\u00dft man Urlaub als Reise zum \u201eIch\u201c . Entschleunigung, Abwesenheit von allem \u00dcberfl\u00fcssigen und das Bewusstsein, mit gutem Gewissen genie\u00dfen zu k\u00f6nnen.<\/strong><\/p>\n\n\n\n<div class=\"wp-block-media-text alignwide is-stacked-on-mobile\"><figure class=\"wp-block-media-text__media\"><img decoding=\"async\" width=\"1000\" height=\"666\" src=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2022\/03\/SAND_Muller.jpg\" alt=\"SAND - Hoteliers\" class=\"wp-image-83012 size-full\" srcset=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2022\/03\/SAND_Muller.jpg 1000w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2022\/03\/SAND_Muller-768x511.jpg 768w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2022\/03\/SAND_Muller-360x240.jpg 360w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure><div class=\"wp-block-media-text__content\">\n<p>Die Leidenschaft und der Wunsch, Gastgeber zu sein waren f\u00fcr Marion und Lambertus Muller der ausschlaggebende Grund ein Hotel zu betreiben. 1995 fanden die beiden das passende Objekt zur Verwirklichung ihres Traums am <strong>Timmendorfer Strand an der deutschen Ostseek\u00fcste<\/strong>.  <\/p>\n<\/div><\/div>\n\n\n\n<h2 class=\"wp-block-heading\">SAND &#8211; Sand Aspires Natural Design<\/h2>\n\n\n\n<p>Das Thema Nachhaltigkeit stand dabei von Beginn an an oberster Stelle.  Man wollte mit der Schaffung einer unkonventionellen SANDwelt basierend auf einem nat\u00fcrlichen, unverwechselbaren und einzigartigen Ambiente, ein besonderes Erlebnis erm\u00f6glichen, dass den Nachhaltigkeitsgedanken mit einbezieht. Zu sp\u00fcren ist das in der konsequenten und innovativen Umsetzung in allen Bereichen bis hin zu den angebotenen Dienstleistungen.<\/p>\n\n\n\n<p>Fast alles im SAND ist aus Naturprodukten vom Interieur bis in die K\u00fcche.  Entdecken Sie die klare Linie, die sich hinter der SAND Philosophie verbirgt und machen Sie Ihren Urlaub zu einer Zeit grenzenloser M\u00f6glichkeiten des Erlebens und Genie\u00dfens. Freuen Sie sich auf eine ungezwungene Auszeit und lassen Sie sich verw\u00f6hnen bei ausgezeichnetem Service des ambitionierten Teams in stilvoller Atmosph\u00e4re voller Leichtigkeit&nbsp;und Weitblick.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Der Gast<\/h2>\n\n\n\n<p>Die G\u00e4ste im <a href=\"https:\/\/www.lifestylehotels.net\/de\/hotel\/sand\/\">SAND<\/a> sprechen auf das<strong>&nbsp;Nachhaltigkeitskonzept in Verbindung mit Lifestyle und Wellness<\/strong> an. Ein Lebensstil und Konsumententyp, der sich an Gesundheit, intakter Natur, Lebensqualit\u00e4t und globaler Gerechtigkeit orientiert. Bei der Ansprache dieser heterogenen Zielgruppe spielen soziografische Aspekte im Gegensatz zu demografischen Werten eine tragende Rolle. In der Fachliteratur werden die so identifizierten Personen als <a href=\"https:\/\/de.wikipedia.org\/wiki\/LOHAS\" target=\"_blank\" rel=\"noreferrer noopener\">&#8222;LOHAS&#8220; (Lifestyle of Health and Sustainability) <\/a>bezeichnet.&nbsp;Das sind <strong>Erholungssuchende \u2013 Paare, wie Einzelreisende oder Gesch\u00e4ftsreisende, die Wert auf Individualit\u00e4t, Lifestyle und Nachhaltigkeit lege<\/strong>n.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"900\" height=\"500\" src=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2022\/03\/LIFESTYLEHOTEL-Sand-7-web.jpg\" alt=\"SAND - relax\" class=\"wp-image-82979\" srcset=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2022\/03\/LIFESTYLEHOTEL-Sand-7-web.jpg 900w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2022\/03\/LIFESTYLEHOTEL-Sand-7-web-768x427.jpg 768w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2022\/03\/LIFESTYLEHOTEL-Sand-7-web-360x200.jpg 360w\" sizes=\"(max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<p>Aktivit\u00e4ten &#8211; outdoor und indoor &#8211; schaffen Ausgleich und Entspannung. Zeit zum Relaxen hat man auf der <strong>Dachterrasse mit Au\u00dfensauna und Aussichtsplattform<\/strong>. SAND activities findet man am Strand oder beim Erkunden der zahlreichen Ausflugsziele in und um Timmendorfer Strand.<\/p>\n\n\n\n<p> <strong><a href=\"https:\/\/www.lifestylehotels.net\/de\/hotel\/sand\/\" target=\"_blank\" rel=\"noreferrer noopener\">SAND <\/a>is a Member of <a href=\"https:\/\/www.lifestylehotels.net\/de\/\" target=\"_blank\" rel=\"noreferrer noopener\">Lifestylehotels<\/a><\/strong> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im SAND, das nur einige Gehminuten vom Timmendorfer Strand entfernt liegt, genie\u00dft man Urlaub als Reise zum \u201eIch\u201c . Entschleunigung, Abwesenheit von allem \u00dcberfl\u00fcssigen und das Bewusstsein, mit gutem Gewissen genie\u00dfen zu k\u00f6nnen.<\/p>\n","protected":false},"author":9,"featured_media":66930,"template":"","meta":{"inline_featured_image":false},"categories":[2273],"tags":[2352,3135,3134,2350],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.9.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>SAND: Entspannung mit Weitblick - Lifestylehotels\u2122<\/title>\n<meta name=\"description\" content=\"Im SAND, das nur einige Gehminuten vom Timmendorfer Strand entfernt liegt, genie\u00dft man Urlaub als Reise zum \u201eIch\u201c.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lifestylehotels.net\/de\/story\/sand-timmendorfer-strand-deutschland-entspannung-mit-weitblick\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"SAND: Entspannung mit Weitblick - Lifestylehotels\u2122\" \/>\n<meta property=\"og:description\" content=\"Im SAND, das nur einige Gehminuten vom Timmendorfer Strand entfernt liegt, genie\u00dft man Urlaub als Reise zum \u201eIch\u201c.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lifestylehotels.net\/de\/story\/sand-timmendorfer-strand-deutschland-entspannung-mit-weitblick\/\" \/>\n<meta property=\"og:site_name\" content=\"Lifestylehotels\u2122\" \/>\n<meta property=\"article:modified_time\" content=\"2022-03-10T10:54:42+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2020\/12\/philipp-cWHMyEA2wMU-unsplash.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2250\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lifestylehotels.net\/de\/story\/sand-timmendorfer-strand-deutschland-entspannung-mit-weitblick\/\",\"url\":\"https:\/\/www.lifestylehotels.net\/de\/story\/sand-timmendorfer-strand-deutschland-entspannung-mit-weitblick\/\",\"name\":\"SAND: Entspannung mit Weitblick - Lifestylehotels\u2122\",\"isPartOf\":{\"@id\":\"https:\/\/www.lifestylehotels.net\/de\/#website\"},\"datePublished\":\"2020-12-30T12:22:01+00:00\",\"dateModified\":\"2022-03-10T10:54:42+00:00\",\"description\":\"Im SAND, das nur einige Gehminuten vom Timmendorfer Strand entfernt liegt, genie\u00dft man Urlaub als Reise zum \u201eIch\u201c.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lifestylehotels.net\/de\/story\/sand-timmendorfer-strand-deutschland-entspannung-mit-weitblick\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lifestylehotels.net\/de\/story\/sand-timmendorfer-strand-deutschland-entspannung-mit-weitblick\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lifestylehotels.net\/de\/story\/sand-timmendorfer-strand-deutschland-entspannung-mit-weitblick\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.lifestylehotels.net\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SAND, Timmendorfer Strand, Deutschland: Entspannung mit Weitblick\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lifestylehotels.net\/de\/#website\",\"url\":\"https:\/\/www.lifestylehotels.net\/de\/\",\"name\":\"Lifestylehotels\u2122\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lifestylehotels.net\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"SAND: Entspannung mit Weitblick - Lifestylehotels\u2122","description":"Im SAND, das nur einige Gehminuten vom Timmendorfer Strand entfernt liegt, genie\u00dft man Urlaub als Reise zum \u201eIch\u201c.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lifestylehotels.net\/de\/story\/sand-timmendorfer-strand-deutschland-entspannung-mit-weitblick\/","og_locale":"de_DE","og_type":"article","og_title":"SAND: Entspannung mit Weitblick - Lifestylehotels\u2122","og_description":"Im SAND, das nur einige Gehminuten vom Timmendorfer Strand entfernt liegt, genie\u00dft man Urlaub als Reise zum \u201eIch\u201c.","og_url":"https:\/\/www.lifestylehotels.net\/de\/story\/sand-timmendorfer-strand-deutschland-entspannung-mit-weitblick\/","og_site_name":"Lifestylehotels\u2122","article_modified_time":"2022-03-10T10:54:42+00:00","og_image":[{"width":2250,"height":1500,"url":"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2020\/12\/philipp-cWHMyEA2wMU-unsplash.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.lifestylehotels.net\/de\/story\/sand-timmendorfer-strand-deutschland-entspannung-mit-weitblick\/","url":"https:\/\/www.lifestylehotels.net\/de\/story\/sand-timmendorfer-strand-deutschland-entspannung-mit-weitblick\/","name":"SAND: Entspannung mit Weitblick - Lifestylehotels\u2122","isPartOf":{"@id":"https:\/\/www.lifestylehotels.net\/de\/#website"},"datePublished":"2020-12-30T12:22:01+00:00","dateModified":"2022-03-10T10:54:42+00:00","description":"Im SAND, das nur einige Gehminuten vom Timmendorfer Strand entfernt liegt, genie\u00dft man Urlaub als Reise zum \u201eIch\u201c.","breadcrumb":{"@id":"https:\/\/www.lifestylehotels.net\/de\/story\/sand-timmendorfer-strand-deutschland-entspannung-mit-weitblick\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lifestylehotels.net\/de\/story\/sand-timmendorfer-strand-deutschland-entspannung-mit-weitblick\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.lifestylehotels.net\/de\/story\/sand-timmendorfer-strand-deutschland-entspannung-mit-weitblick\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.lifestylehotels.net\/de\/"},{"@type":"ListItem","position":2,"name":"SAND, Timmendorfer Strand, Deutschland: Entspannung mit Weitblick"}]},{"@type":"WebSite","@id":"https:\/\/www.lifestylehotels.net\/de\/#website","url":"https:\/\/www.lifestylehotels.net\/de\/","name":"Lifestylehotels\u2122","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lifestylehotels.net\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lifestylehotels.net\/de\/wp-json\/wp\/v2\/stories\/43809"}],"collection":[{"href":"https:\/\/www.lifestylehotels.net\/de\/wp-json\/wp\/v2\/stories"}],"about":[{"href":"https:\/\/www.lifestylehotels.net\/de\/wp-json\/wp\/v2\/types\/stories"}],"author":[{"embeddable":true,"href":"https:\/\/www.lifestylehotels.net\/de\/wp-json\/wp\/v2\/users\/9"}],"version-history":[{"count":23,"href":"https:\/\/www.lifestylehotels.net\/de\/wp-json\/wp\/v2\/stories\/43809\/revisions"}],"predecessor-version":[{"id":87166,"href":"https:\/\/www.lifestylehotels.net\/de\/wp-json\/wp\/v2\/stories\/43809\/revisions\/87166"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lifestylehotels.net\/de\/wp-json\/wp\/v2\/media\/66930"}],"wp:attachment":[{"href":"https:\/\/www.lifestylehotels.net\/de\/wp-json\/wp\/v2\/media?parent=43809"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lifestylehotels.net\/de\/wp-json\/wp\/v2\/categories?post=43809"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lifestylehotels.net\/de\/wp-json\/wp\/v2\/tags?post=43809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}