{"id":671771,"date":"2024-01-12T09:33:59","date_gmt":"2024-01-12T08:33:59","guid":{"rendered":"https:\/\/www.lifestylehotels.net\/?post_type=stories&#038;p=671771"},"modified":"2024-01-12T09:53:33","modified_gmt":"2024-01-12T08:53:33","slug":"apuliens-borghi-slow-living-als-lebensphilosophie","status":"publish","type":"stories","link":"https:\/\/www.lifestylehotels.net\/de\/story\/apuliens-borghi-slow-living-als-lebensphilosophie\/","title":{"rendered":"Apuliens Borghi \u2013 Slow Living als Lebensphilosophie"},"content":{"rendered":"\n<p><strong>Apulien \u2013 die Adria im Norden, das Ionische Meer im S\u00fcden, eine 800 Kilometer lange K\u00fcste, knorrige Olivenb\u00e4ume, Weinberge. Sehnsuchtsort Reisender auf der Suche nach dem s\u00fc\u00dfen Leben. Dem Erleben, dem Genuss, dem Hier und Jetzt wird hier Zeit gegeben \u2013 einfach <em>La Vita <\/em>gelebt. Diese Lebensphilosophie bezeichnet man heute auch als Slow Living. Eine einfache Art, das Leben zu genie\u00dfen.<\/strong><\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"2250\" height=\"1500\" src=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/01\/luca-micheli-42fS8_aq5oQ-unsplash-scaled.jpg\" alt=\"\" class=\"wp-image-671777\" srcset=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/01\/luca-micheli-42fS8_aq5oQ-unsplash-scaled.jpg 2250w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/01\/luca-micheli-42fS8_aq5oQ-unsplash-768x512.jpg 768w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/01\/luca-micheli-42fS8_aq5oQ-unsplash-1536x1024.jpg 1536w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/01\/luca-micheli-42fS8_aq5oQ-unsplash-2048x1365.jpg 2048w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/01\/luca-micheli-42fS8_aq5oQ-unsplash-360x240.jpg 360w\" sizes=\"(max-width: 2250px) 100vw, 2250px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Urspr\u00fcnglich &amp; unber\u00fchrt<\/h2>\n\n\n\n<p>Nur wenige gr\u00f6\u00dfere St\u00e4dte sind in Apulien zu finden. Beispielsweise Bari, Tarent und Lecce. Den Charme dieser Region machen viele kleine, mittelalterlich anmutende D\u00f6rfer mit reicher Geschichte und Tradition aus. Reisende, die die Essenz dieser urspr\u00fcnglichen und unber\u00fchrten Region erleben m\u00f6chten, machen sich auf die Suche nach genau diesen Orten. Fern vom Massentourismus erlebt man in den sogenannten Borghi das authentische Apulien.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"2250\" height=\"1500\" src=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/01\/daniel-corneschi-Xn3wf_0Il2k-unsplash-scaled.jpg\" alt=\"\" class=\"wp-image-671779\" srcset=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/01\/daniel-corneschi-Xn3wf_0Il2k-unsplash-scaled.jpg 2250w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/01\/daniel-corneschi-Xn3wf_0Il2k-unsplash-768x512.jpg 768w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/01\/daniel-corneschi-Xn3wf_0Il2k-unsplash-1536x1024.jpg 1536w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/01\/daniel-corneschi-Xn3wf_0Il2k-unsplash-2048x1365.jpg 2048w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/01\/daniel-corneschi-Xn3wf_0Il2k-unsplash-360x240.jpg 360w\" sizes=\"(max-width: 2250px) 100vw, 2250px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">\u00dcbernachten in den H\u00f6hlen von Matera<\/h2>\n\n\n\n<p>Eines dieser Borghi ist Matera: UNESCO Weltkulturerbe seit 1993 und Kulturhauptstadt Europas 2019. Die Geschichte der Kleinstadt ist wortw\u00f6rtlich in Stein gemei\u00dfelt. Bis in die 1950er Jahre lebte man in den Sassi di Matera, H\u00f6hlensiedlungen, die an den Felsenh\u00e4ngen gebaut wurden.<\/p>\n\n\n\n<p>Eine dieser H\u00f6hlensiedlungen ist heute das <a href=\"https:\/\/www.lifestylehotels.net\/de\/hotel\/sextantio-le-grotte-della-civita\/\" target=\"_blank\" rel=\"noreferrer noopener\">Hotel Sextantio Le Grotte della Civita<\/a>. Ein kulturelles Projekt, das zur Wiederherstellung alter H\u00f6hlen gestartet wurde. Von den Boutique Zimmern und Suiten aus genie\u00dft man hier einen spektakul\u00e4ren Blick auf die Gravina Schlucht und die Kulisse des Murgia-Parks.<\/p>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"720\" height=\"960\" data-id=\"671781\" src=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/01\/36417407_2096672727012783_8255168034742730752_n.jpg\" alt=\"\" class=\"wp-image-671781\" srcset=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/01\/36417407_2096672727012783_8255168034742730752_n.jpg 720w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/01\/36417407_2096672727012783_8255168034742730752_n-360x480.jpg 360w\" sizes=\"(max-width: 720px) 100vw, 720px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1125\" height=\"1500\" data-id=\"671783\" src=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/01\/A-3347-scaled.jpg\" alt=\"\" class=\"wp-image-671783\" srcset=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/01\/A-3347-scaled.jpg 1125w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/01\/A-3347-768x1024.jpg 768w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/01\/A-3347-360x480.jpg 360w\" sizes=\"(max-width: 1125px) 100vw, 1125px\" \/><\/figure>\n<\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Apuliens Quintessenz<\/h2>\n\n\n\n<p>Zur Lebensphilosophie und den Freuden von <em>La Vita<\/em> geh\u00f6rt f\u00fcr die S\u00fcditaliener auch das Essen. Und hier ist Apulien Meister der Einfachheit: Traditionell ist, was regional und saisonal ist \u2013 von Oliven\u00f6l, Fisch, Meeresfr\u00fcchte, Burrata \u00fcber Orecchiette, Focaccia aus dem Holzofen, bis hin zu Zitrusfr\u00fcchten, Tomaten und Auberginen.<\/p>\n\n\n\n<p>So auch im Borghi Ostuni \u2013 oft die wei\u00dfe Stadt genannt. Die wei\u00dfen H\u00e4user der Kleinstadt thronen auf einem H\u00fcgel umgeben von Jahrhundert alten Olivenhainen. Oliven\u00f6l in feinster Ausf\u00fchrung wird hier von lokalen \u00d6lm\u00fchlen hergestellt.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"2500\" height=\"1406\" src=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/01\/4EEACB35-26E3-4CA5-A4DC-EDF2BCE76A6C-scaled.jpg\" alt=\"\" class=\"wp-image-671786\" srcset=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/01\/4EEACB35-26E3-4CA5-A4DC-EDF2BCE76A6C-scaled.jpg 2500w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/01\/4EEACB35-26E3-4CA5-A4DC-EDF2BCE76A6C-768x432.jpg 768w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/01\/4EEACB35-26E3-4CA5-A4DC-EDF2BCE76A6C-1536x864.jpg 1536w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/01\/4EEACB35-26E3-4CA5-A4DC-EDF2BCE76A6C-2048x1152.jpg 2048w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/01\/4EEACB35-26E3-4CA5-A4DC-EDF2BCE76A6C-360x203.jpg 360w\" sizes=\"(max-width: 2500px) 100vw, 2500px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\">Hoteltipp im Zentrum von Ostuni<\/h2>\n\n\n\n<p>Im Herzen Ostunis befindet sich auch das <a href=\"https:\/\/www.lifestylehotels.net\/de\/hotel\/paragon-700-boutique-hotel-spa\/\" target=\"_blank\" rel=\"noreferrer noopener\">Paragon 700 Boutique Hotel &amp; Spa<\/a>. Im urspr\u00fcnglichen Palazzo mit Gew\u00f6lbe und einstiger \u00d6lm\u00fchle erleben G\u00e4ste apulische Gourmetk\u00fcche im wahrsten Sinne des Wortes. Oliven\u00f6l ist auch hier allgegenwertig, denn das Herz des Restaurants bildet ein alter Olivenm\u00fchlenstein der zu einem gro\u00dfen, geselligen Tisch im kreativen Design umfunktioniert wurde.<\/p>\n\n\n\n<p>Farm-to-Table-Konzept: Im Ristorante 700 stehen lokale Produkte von einheimischen Bauern und die Vielfalt der saisonalen Geschm\u00e4cker im Fokus. Daraus entstehen regional beeinflusste Gerichte, die G\u00e4ste auf eine geschmackliche Reise zwischen Tradition und Zukunft schicken.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"2251\" height=\"1500\" src=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/01\/A00C808B-67F4-4C19-AA4A-79EE037AF930-scaled.jpg\" alt=\"\" class=\"wp-image-671788\" srcset=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/01\/A00C808B-67F4-4C19-AA4A-79EE037AF930-scaled.jpg 2251w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/01\/A00C808B-67F4-4C19-AA4A-79EE037AF930-768x512.jpg 768w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/01\/A00C808B-67F4-4C19-AA4A-79EE037AF930-1536x1024.jpg 1536w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/01\/A00C808B-67F4-4C19-AA4A-79EE037AF930-2048x1365.jpg 2048w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/01\/A00C808B-67F4-4C19-AA4A-79EE037AF930-360x240.jpg 360w\" sizes=\"(max-width: 2251px) 100vw, 2251px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1001\" height=\"1500\" data-id=\"671792\" src=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/01\/DSC4760-scaled.jpg\" alt=\"\" class=\"wp-image-671792\" srcset=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/01\/DSC4760-scaled.jpg 1001w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/01\/DSC4760-768x1151.jpg 768w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/01\/DSC4760-1366x2048.jpg 1000w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/01\/DSC4760-360x540.jpg 360w\" sizes=\"(max-width: 1001px) 100vw, 1001px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1000\" height=\"1500\" data-id=\"671790\" src=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/01\/B8CA29EE-BE22-442E-92C5-E2112692287B-scaled.jpg\" alt=\"\" class=\"wp-image-671790\" srcset=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/01\/B8CA29EE-BE22-442E-92C5-E2112692287B-scaled.jpg 1000w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/01\/B8CA29EE-BE22-442E-92C5-E2112692287B-768x1152.jpg 768w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/01\/B8CA29EE-BE22-442E-92C5-E2112692287B-360x540.jpg 360w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n<\/figure>\n","protected":false},"excerpt":{"rendered":"<p>Apulien \u2013 die Adria im Norden, das Ionische Meer im S\u00fcden, eine 800 Kilometer lange K\u00fcste, knorrige Olivenb\u00e4ume, Weinberge. Sehnsuchtsort Reisender auf der Suche nach dem s\u00fc\u00dfen Leben. <\/p>\n","protected":false},"author":4,"featured_media":671777,"template":"","meta":{"inline_featured_image":false},"categories":[3658],"tags":[3997,3999,2501,4001,3877,3745,4002,3998],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.9.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Apuliens Borghi \u2013 Slow Living als Lebensphilosophie - Lifestylehotels\u2122<\/title>\n<meta name=\"description\" content=\"Apulien \u2013 die Adria im Norden, das Ionische Meer im S\u00fcden, eine 800 Kilometer lange K\u00fcste, knorrige Olivenb\u00e4ume, Weinberge. Sehnsuchtsort Reisender auf der Suche nach dem s\u00fc\u00dfen Leben.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lifestylehotels.net\/de\/story\/apuliens-borghi-slow-living-als-lebensphilosophie\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Apuliens Borghi \u2013 Slow Living als Lebensphilosophie - Lifestylehotels\u2122\" \/>\n<meta property=\"og:description\" content=\"Apulien \u2013 die Adria im Norden, das Ionische Meer im S\u00fcden, eine 800 Kilometer lange K\u00fcste, knorrige Olivenb\u00e4ume, Weinberge. Sehnsuchtsort Reisender auf der Suche nach dem s\u00fc\u00dfen Leben.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lifestylehotels.net\/de\/story\/apuliens-borghi-slow-living-als-lebensphilosophie\/\" \/>\n<meta property=\"og:site_name\" content=\"Lifestylehotels\u2122\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-12T08:53:33+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/01\/luca-micheli-42fS8_aq5oQ-unsplash-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2250\" \/>\n\t<meta property=\"og:image:height\" content=\"1500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lifestylehotels.net\/de\/story\/apuliens-borghi-slow-living-als-lebensphilosophie\/\",\"url\":\"https:\/\/www.lifestylehotels.net\/de\/story\/apuliens-borghi-slow-living-als-lebensphilosophie\/\",\"name\":\"Apuliens Borghi \u2013 Slow Living als Lebensphilosophie - Lifestylehotels\u2122\",\"isPartOf\":{\"@id\":\"https:\/\/www.lifestylehotels.net\/de\/#website\"},\"datePublished\":\"2024-01-12T08:33:59+00:00\",\"dateModified\":\"2024-01-12T08:53:33+00:00\",\"description\":\"Apulien \u2013 die Adria im Norden, das Ionische Meer im S\u00fcden, eine 800 Kilometer lange K\u00fcste, knorrige Olivenb\u00e4ume, Weinberge. Sehnsuchtsort Reisender auf der Suche nach dem s\u00fc\u00dfen Leben.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lifestylehotels.net\/de\/story\/apuliens-borghi-slow-living-als-lebensphilosophie\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lifestylehotels.net\/de\/story\/apuliens-borghi-slow-living-als-lebensphilosophie\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lifestylehotels.net\/de\/story\/apuliens-borghi-slow-living-als-lebensphilosophie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.lifestylehotels.net\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Apuliens Borghi \u2013 Slow Living als Lebensphilosophie\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lifestylehotels.net\/de\/#website\",\"url\":\"https:\/\/www.lifestylehotels.net\/de\/\",\"name\":\"Lifestylehotels\u2122\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lifestylehotels.net\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Apuliens Borghi \u2013 Slow Living als Lebensphilosophie - Lifestylehotels\u2122","description":"Apulien \u2013 die Adria im Norden, das Ionische Meer im S\u00fcden, eine 800 Kilometer lange K\u00fcste, knorrige Olivenb\u00e4ume, Weinberge. Sehnsuchtsort Reisender auf der Suche nach dem s\u00fc\u00dfen Leben.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lifestylehotels.net\/de\/story\/apuliens-borghi-slow-living-als-lebensphilosophie\/","og_locale":"de_DE","og_type":"article","og_title":"Apuliens Borghi \u2013 Slow Living als Lebensphilosophie - Lifestylehotels\u2122","og_description":"Apulien \u2013 die Adria im Norden, das Ionische Meer im S\u00fcden, eine 800 Kilometer lange K\u00fcste, knorrige Olivenb\u00e4ume, Weinberge. Sehnsuchtsort Reisender auf der Suche nach dem s\u00fc\u00dfen Leben.","og_url":"https:\/\/www.lifestylehotels.net\/de\/story\/apuliens-borghi-slow-living-als-lebensphilosophie\/","og_site_name":"Lifestylehotels\u2122","article_modified_time":"2024-01-12T08:53:33+00:00","og_image":[{"width":2250,"height":1500,"url":"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/01\/luca-micheli-42fS8_aq5oQ-unsplash-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.lifestylehotels.net\/de\/story\/apuliens-borghi-slow-living-als-lebensphilosophie\/","url":"https:\/\/www.lifestylehotels.net\/de\/story\/apuliens-borghi-slow-living-als-lebensphilosophie\/","name":"Apuliens Borghi \u2013 Slow Living als Lebensphilosophie - Lifestylehotels\u2122","isPartOf":{"@id":"https:\/\/www.lifestylehotels.net\/de\/#website"},"datePublished":"2024-01-12T08:33:59+00:00","dateModified":"2024-01-12T08:53:33+00:00","description":"Apulien \u2013 die Adria im Norden, das Ionische Meer im S\u00fcden, eine 800 Kilometer lange K\u00fcste, knorrige Olivenb\u00e4ume, Weinberge. Sehnsuchtsort Reisender auf der Suche nach dem s\u00fc\u00dfen Leben.","breadcrumb":{"@id":"https:\/\/www.lifestylehotels.net\/de\/story\/apuliens-borghi-slow-living-als-lebensphilosophie\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lifestylehotels.net\/de\/story\/apuliens-borghi-slow-living-als-lebensphilosophie\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.lifestylehotels.net\/de\/story\/apuliens-borghi-slow-living-als-lebensphilosophie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.lifestylehotels.net\/de\/"},{"@type":"ListItem","position":2,"name":"Apuliens Borghi \u2013 Slow Living als Lebensphilosophie"}]},{"@type":"WebSite","@id":"https:\/\/www.lifestylehotels.net\/de\/#website","url":"https:\/\/www.lifestylehotels.net\/de\/","name":"Lifestylehotels\u2122","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lifestylehotels.net\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lifestylehotels.net\/de\/wp-json\/wp\/v2\/stories\/671771"}],"collection":[{"href":"https:\/\/www.lifestylehotels.net\/de\/wp-json\/wp\/v2\/stories"}],"about":[{"href":"https:\/\/www.lifestylehotels.net\/de\/wp-json\/wp\/v2\/types\/stories"}],"author":[{"embeddable":true,"href":"https:\/\/www.lifestylehotels.net\/de\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":9,"href":"https:\/\/www.lifestylehotels.net\/de\/wp-json\/wp\/v2\/stories\/671771\/revisions"}],"predecessor-version":[{"id":671805,"href":"https:\/\/www.lifestylehotels.net\/de\/wp-json\/wp\/v2\/stories\/671771\/revisions\/671805"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lifestylehotels.net\/de\/wp-json\/wp\/v2\/media\/671777"}],"wp:attachment":[{"href":"https:\/\/www.lifestylehotels.net\/de\/wp-json\/wp\/v2\/media?parent=671771"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lifestylehotels.net\/de\/wp-json\/wp\/v2\/categories?post=671771"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lifestylehotels.net\/de\/wp-json\/wp\/v2\/tags?post=671771"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}