{"id":672491,"date":"2024-02-13T10:06:41","date_gmt":"2024-02-13T09:06:41","guid":{"rendered":"https:\/\/www.lifestylehotels.net\/?post_type=stories&#038;p=672491"},"modified":"2024-02-13T10:06:44","modified_gmt":"2024-02-13T09:06:44","slug":"ein-wolfuehlnest-am-wiesenhang-hotel-nidum","status":"publish","type":"stories","link":"https:\/\/www.lifestylehotels.net\/de\/story\/ein-wolfuehlnest-am-wiesenhang-hotel-nidum\/","title":{"rendered":"Ein Wolf\u00fchlnest am Wiesenhang, Hotel Nidum"},"content":{"rendered":"\n<p>Wie es sich wohl anf\u00fchlen muss, hoch oben in einem warmen Nest zu sitzen? Im <strong><a href=\"https:\/\/www.nidum-hotel.com\/\" target=\"_blank\" rel=\"noreferrer noopener\">Nidum<\/a><\/strong> wei\u00df man das ganz genau. Es ist nat\u00fcrlich kein Zufall, dass das Luxushotel so hei\u00dft, wie die lateinische Bezeichnung f\u00fcr den tierischen R\u00fcckzugsort. Der <a href=\"https:\/\/www.thestylemate.com\/?s=mindful+traveller\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Mindful Traveller<\/strong><\/a>, der sich hier einnistet, genie\u00dft <a href=\"https:\/\/www.thestylemate.com\/?s=wellness\" target=\"_blank\" rel=\"noreferrer noopener\">Wellness<\/a> fernab des Alltagstrubels.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Ankommen<\/h2>\n\n\n\n<figure class=\"wp-block-image\"><img decoding=\"async\" src=\"https:\/\/i1.wp.com\/www.thestylemate.com\/wp-content\/uploads\/387851174_719935576839844_8729793234873405257_n-1024x1024.jpg?ssl=1\" alt=\"Nidum\"\/><\/figure>\n\n\n\n<p>Wer die Adresse Am Wiesenhang in Tirol eingibt, wird dieses Ziel wortw\u00f6rtlich erreichen: einen Wiesenhang am Waldrand umgeben von einer traumhaften Bergkulisse. Ein versteckter Weg zwischen den B\u00e4umen, f\u00fchrt zu einem beschaulichen See. Die Sch\u00f6nheit des Seefelder Plateaus fordert nahezu dazu auf, ein erstes Mal tief durchzuatmen. Das Haus mit der Fassade, die an liebevoll zusammengetragene \u00c4stchen erinnert, ist das <a href=\"https:\/\/www.thestylemate.com\/?s=nidum\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Nidum<\/strong><\/a>. Es f\u00fchlt sich sichtlich wohl in seinem Hang und wartet geduldig darauf, seine G\u00e4ste bei sich aufzunehmen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Entspannen<\/h2>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"2003\" height=\"1500\" src=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/02\/hotel-nidum-upscale-allgemein-26-scaled.jpg\" alt=\"\" class=\"wp-image-672504\" srcset=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/02\/hotel-nidum-upscale-allgemein-26-scaled.jpg 2003w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/02\/hotel-nidum-upscale-allgemein-26-768x575.jpg 768w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/02\/hotel-nidum-upscale-allgemein-26-1536x1150.jpg 1536w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/02\/hotel-nidum-upscale-allgemein-26-360x270.jpg 360w\" sizes=\"(max-width: 2003px) 100vw, 2003px\" \/><\/figure>\n\n\n\n<p>Das zweite Durchatmen kommt, wenn man das <a href=\"https:\/\/www.nidum-hotel.com\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>Nidum<\/strong><\/a> betritt. Ab jetzt d\u00fcrfen alle Sorgen drau\u00dfen bleiben. An nichts denken, nur an sich \u2013 hei\u00dft es hier. Wo k\u00f6nnte so etwas besser gelingen als bei einer <em><a href=\"https:\/\/www.nidum-hotel.com\/wellnesshotel-oesterreich\/beauty-massagen\" target=\"_blank\" rel=\"noreferrer noopener\">Beauty oder Massagebehandlung<\/a><\/em>? Kr\u00e4uterfu\u00dfbad, Hot Stone, Massage mit Zirben-Honig-Milch oder Ganzk\u00f6rperpeeling, wie h\u00f6rt sich das an?<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Treiben lassen<\/h2>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"683\" height=\"1024\" data-id=\"672492\" src=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/02\/nidum1.webp\" alt=\"\" class=\"wp-image-672492\" srcset=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/02\/nidum1.webp 683w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/02\/nidum1-360x540.webp 360w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1024\" height=\"767\" data-id=\"672496\" src=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/02\/nidum2.webp\" alt=\"\" class=\"wp-image-672496\" srcset=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/02\/nidum2.webp 1024w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/02\/nidum2-768x575.webp 768w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/02\/nidum2-360x270.webp 360w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"683\" height=\"1024\" data-id=\"672494\" src=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/02\/nidum3.webp\" alt=\"\" class=\"wp-image-672494\" srcset=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/02\/nidum3.webp 683w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/02\/nidum3-360x540.webp 360w\" sizes=\"(max-width: 683px) 100vw, 683px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>Nun, wie w\u00e4re es jetzt mit ein bisschen <a href=\"https:\/\/www.thestylemate.com\/?s=wasser\" target=\"_blank\" rel=\"noreferrer noopener\"><em>Wasser<\/em><\/a>? In dreifacher Ausf\u00fchrung kommt man im <a href=\"https:\/\/www.nidum-hotel.com\/wellnesshotel-oesterreich\/pools\"><strong>Nidum<\/strong><\/a> mit dem Element in Verbindung. Im beheizten Whirlpool auf der Terrasse werden Verspannungen weggeblubbert. Im gr\u00fcnen Naturbadeteich verschmilzt man mit der waldigen Umgebung und wird so Teil der atemberaubenden Kulisse. Und im Infinity Pool darf die Entspannung ins Unendliche gehen.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Kraft sch\u00f6pfen<\/h2>\n\n\n\n<figure class=\"wp-block-gallery has-nested-images columns-default is-cropped wp-block-gallery-2 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1000\" height=\"1500\" data-id=\"672500\" src=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/02\/hotel-nidum-upscale-allgemein-36-scaled.jpg\" alt=\"\" class=\"wp-image-672500\" srcset=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/02\/hotel-nidum-upscale-allgemein-36-scaled.jpg 1000w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/02\/hotel-nidum-upscale-allgemein-36-768x1152.jpg 768w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/02\/hotel-nidum-upscale-allgemein-36-360x540.jpg 360w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1000\" height=\"1500\" data-id=\"672502\" src=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/02\/hotel-nidum-upscale-allgemein-37-scaled.jpg\" alt=\"\" class=\"wp-image-672502\" srcset=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/02\/hotel-nidum-upscale-allgemein-37-scaled.jpg 1000w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/02\/hotel-nidum-upscale-allgemein-37-768x1152.jpg 768w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/02\/hotel-nidum-upscale-allgemein-37-360x540.jpg 360w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n\n\n\n<figure class=\"wp-block-image size-large\"><img decoding=\"async\" width=\"1000\" height=\"1500\" data-id=\"672498\" src=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/02\/hotel-nidum-upscale-allgemein-49-scaled.jpg\" alt=\"\" class=\"wp-image-672498\" srcset=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/02\/hotel-nidum-upscale-allgemein-49-scaled.jpg 1000w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/02\/hotel-nidum-upscale-allgemein-49-768x1152.jpg 768w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/02\/hotel-nidum-upscale-allgemein-49-360x540.jpg 360w\" sizes=\"(max-width: 1000px) 100vw, 1000px\" \/><\/figure>\n<\/figure>\n\n\n\n<p>W\u00e4hrend man im Alltagstrubel besser nicht ins Schwitzen kommen sollte, wird man hier dazu sogar aufgefordert. Ein <em><a href=\"https:\/\/www.thestylemate.com\/?s=fitness\">Fitness<\/a>raum<\/em> sorgt f\u00fcr Pulsbeschleunigungen der positiven Art. Und dann sind da noch die <a href=\"https:\/\/www.nidum-hotel.com\/wellnesshotel-oesterreich\/saunas\"><em>Saunen<\/em><\/a>, und zwar in der Mehrzahl, denn davon gibt es gleich vier. Die spektakul\u00e4rste von ihnen ist in einen Fels eingebaut und \u00fcber eine H\u00e4ngebr\u00fccke erreichbar. Sie wird liebevoll Sauna on the Rocks genannt. Apropos\u2026von hier ist es dann auch gar nicht mehr weit zur Bar, wo jeder entspannende Nidum Tag enden sollte\u2026 Cheers!<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"2003\" height=\"1500\" src=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/02\/hotel-nidum-upscale-allgemein-28-scaled.jpg\" alt=\"\" class=\"wp-image-672506\" srcset=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/02\/hotel-nidum-upscale-allgemein-28-scaled.jpg 2003w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/02\/hotel-nidum-upscale-allgemein-28-768x575.jpg 768w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/02\/hotel-nidum-upscale-allgemein-28-1536x1150.jpg 1536w, https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/02\/hotel-nidum-upscale-allgemein-28-360x270.jpg 360w\" sizes=\"(max-width: 2003px) 100vw, 2003px\" \/><\/figure>\n\n\n\n<p><a href=\"https:\/\/www.lifestylehotels.net\/de\/hotel\/nidum-hotel\/\"><strong>Nidum<\/strong><\/a> is a member of <a href=\"https:\/\/www.lifestylehotels.net\/de\/\"><strong>Lifestylehotels<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wie es sich wohl anf\u00fchlen muss, hoch oben in einem warmen Nest zu sitzen? Im Nidum wei\u00df man das ganz genau. Es ist nat\u00fcrlich kein Zufall, dass das Luxushotel so hei\u00dft, wie die lateinische Bezeichnung f\u00fcr den tierischen R\u00fcckzugsort. Der Mindful Traveller, der sich hier einnistet, genie\u00dft Wellness fernab des Alltagstrubels.<\/p>\n","protected":false},"author":4,"featured_media":672508,"template":"","meta":{"inline_featured_image":false},"categories":[3658],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.9.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ein Wolf\u00fchlnest am Wiesenhang, Hotel Nidum - Lifestylehotels\u2122<\/title>\n<meta name=\"description\" content=\"Wie es sich wohl anf\u00fchlen muss, hoch oben in einem warmen Nest zu sitzen? Im Nidum wei\u00df man das ganz genau. Es ist nat\u00fcrlich kein Zufall, dass das Luxushotel so hei\u00dft, wie die lateinische Bezeichnung f\u00fcr den tierischen R\u00fcckzugsort. Der Mindful Traveller, der sich hier einnistet, genie\u00dft Wellness fernab des Alltagstrubels.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lifestylehotels.net\/de\/story\/ein-wolfuehlnest-am-wiesenhang-hotel-nidum\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ein Wolf\u00fchlnest am Wiesenhang, Hotel Nidum - Lifestylehotels\u2122\" \/>\n<meta property=\"og:description\" content=\"Wie es sich wohl anf\u00fchlen muss, hoch oben in einem warmen Nest zu sitzen? Im Nidum wei\u00df man das ganz genau. Es ist nat\u00fcrlich kein Zufall, dass das Luxushotel so hei\u00dft, wie die lateinische Bezeichnung f\u00fcr den tierischen R\u00fcckzugsort. Der Mindful Traveller, der sich hier einnistet, genie\u00dft Wellness fernab des Alltagstrubels.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lifestylehotels.net\/de\/story\/ein-wolfuehlnest-am-wiesenhang-hotel-nidum\/\" \/>\n<meta property=\"og:site_name\" content=\"Lifestylehotels\u2122\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-13T09:06:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/02\/hotel-nidum-upscale-allgemein-69-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1917\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.lifestylehotels.net\/de\/story\/ein-wolfuehlnest-am-wiesenhang-hotel-nidum\/\",\"url\":\"https:\/\/www.lifestylehotels.net\/de\/story\/ein-wolfuehlnest-am-wiesenhang-hotel-nidum\/\",\"name\":\"Ein Wolf\u00fchlnest am Wiesenhang, Hotel Nidum - Lifestylehotels\u2122\",\"isPartOf\":{\"@id\":\"https:\/\/www.lifestylehotels.net\/de\/#website\"},\"datePublished\":\"2024-02-13T09:06:41+00:00\",\"dateModified\":\"2024-02-13T09:06:44+00:00\",\"description\":\"Wie es sich wohl anf\u00fchlen muss, hoch oben in einem warmen Nest zu sitzen? Im Nidum wei\u00df man das ganz genau. Es ist nat\u00fcrlich kein Zufall, dass das Luxushotel so hei\u00dft, wie die lateinische Bezeichnung f\u00fcr den tierischen R\u00fcckzugsort. Der Mindful Traveller, der sich hier einnistet, genie\u00dft Wellness fernab des Alltagstrubels.\",\"breadcrumb\":{\"@id\":\"https:\/\/www.lifestylehotels.net\/de\/story\/ein-wolfuehlnest-am-wiesenhang-hotel-nidum\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.lifestylehotels.net\/de\/story\/ein-wolfuehlnest-am-wiesenhang-hotel-nidum\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lifestylehotels.net\/de\/story\/ein-wolfuehlnest-am-wiesenhang-hotel-nidum\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.lifestylehotels.net\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ein Wolf\u00fchlnest am Wiesenhang, Hotel Nidum\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lifestylehotels.net\/de\/#website\",\"url\":\"https:\/\/www.lifestylehotels.net\/de\/\",\"name\":\"Lifestylehotels\u2122\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lifestylehotels.net\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ein Wolf\u00fchlnest am Wiesenhang, Hotel Nidum - Lifestylehotels\u2122","description":"Wie es sich wohl anf\u00fchlen muss, hoch oben in einem warmen Nest zu sitzen? Im Nidum wei\u00df man das ganz genau. Es ist nat\u00fcrlich kein Zufall, dass das Luxushotel so hei\u00dft, wie die lateinische Bezeichnung f\u00fcr den tierischen R\u00fcckzugsort. Der Mindful Traveller, der sich hier einnistet, genie\u00dft Wellness fernab des Alltagstrubels.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lifestylehotels.net\/de\/story\/ein-wolfuehlnest-am-wiesenhang-hotel-nidum\/","og_locale":"de_DE","og_type":"article","og_title":"Ein Wolf\u00fchlnest am Wiesenhang, Hotel Nidum - Lifestylehotels\u2122","og_description":"Wie es sich wohl anf\u00fchlen muss, hoch oben in einem warmen Nest zu sitzen? Im Nidum wei\u00df man das ganz genau. Es ist nat\u00fcrlich kein Zufall, dass das Luxushotel so hei\u00dft, wie die lateinische Bezeichnung f\u00fcr den tierischen R\u00fcckzugsort. Der Mindful Traveller, der sich hier einnistet, genie\u00dft Wellness fernab des Alltagstrubels.","og_url":"https:\/\/www.lifestylehotels.net\/de\/story\/ein-wolfuehlnest-am-wiesenhang-hotel-nidum\/","og_site_name":"Lifestylehotels\u2122","article_modified_time":"2024-02-13T09:06:44+00:00","og_image":[{"width":2560,"height":1917,"url":"https:\/\/www.lifestylehotels.net\/wp-content\/uploads\/2024\/02\/hotel-nidum-upscale-allgemein-69-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.lifestylehotels.net\/de\/story\/ein-wolfuehlnest-am-wiesenhang-hotel-nidum\/","url":"https:\/\/www.lifestylehotels.net\/de\/story\/ein-wolfuehlnest-am-wiesenhang-hotel-nidum\/","name":"Ein Wolf\u00fchlnest am Wiesenhang, Hotel Nidum - Lifestylehotels\u2122","isPartOf":{"@id":"https:\/\/www.lifestylehotels.net\/de\/#website"},"datePublished":"2024-02-13T09:06:41+00:00","dateModified":"2024-02-13T09:06:44+00:00","description":"Wie es sich wohl anf\u00fchlen muss, hoch oben in einem warmen Nest zu sitzen? Im Nidum wei\u00df man das ganz genau. Es ist nat\u00fcrlich kein Zufall, dass das Luxushotel so hei\u00dft, wie die lateinische Bezeichnung f\u00fcr den tierischen R\u00fcckzugsort. Der Mindful Traveller, der sich hier einnistet, genie\u00dft Wellness fernab des Alltagstrubels.","breadcrumb":{"@id":"https:\/\/www.lifestylehotels.net\/de\/story\/ein-wolfuehlnest-am-wiesenhang-hotel-nidum\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lifestylehotels.net\/de\/story\/ein-wolfuehlnest-am-wiesenhang-hotel-nidum\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.lifestylehotels.net\/de\/story\/ein-wolfuehlnest-am-wiesenhang-hotel-nidum\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.lifestylehotels.net\/de\/"},{"@type":"ListItem","position":2,"name":"Ein Wolf\u00fchlnest am Wiesenhang, Hotel Nidum"}]},{"@type":"WebSite","@id":"https:\/\/www.lifestylehotels.net\/de\/#website","url":"https:\/\/www.lifestylehotels.net\/de\/","name":"Lifestylehotels\u2122","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lifestylehotels.net\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"}]}},"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.lifestylehotels.net\/de\/wp-json\/wp\/v2\/stories\/672491"}],"collection":[{"href":"https:\/\/www.lifestylehotels.net\/de\/wp-json\/wp\/v2\/stories"}],"about":[{"href":"https:\/\/www.lifestylehotels.net\/de\/wp-json\/wp\/v2\/types\/stories"}],"author":[{"embeddable":true,"href":"https:\/\/www.lifestylehotels.net\/de\/wp-json\/wp\/v2\/users\/4"}],"version-history":[{"count":2,"href":"https:\/\/www.lifestylehotels.net\/de\/wp-json\/wp\/v2\/stories\/672491\/revisions"}],"predecessor-version":[{"id":672511,"href":"https:\/\/www.lifestylehotels.net\/de\/wp-json\/wp\/v2\/stories\/672491\/revisions\/672511"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lifestylehotels.net\/de\/wp-json\/wp\/v2\/media\/672508"}],"wp:attachment":[{"href":"https:\/\/www.lifestylehotels.net\/de\/wp-json\/wp\/v2\/media?parent=672491"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lifestylehotels.net\/de\/wp-json\/wp\/v2\/categories?post=672491"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lifestylehotels.net\/de\/wp-json\/wp\/v2\/tags?post=672491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}