{"id":5029,"count":0,"description":"","link":"https:\/\/www.lifestylehotels.net\/en\/tag\/sierra-calderona-en\/","name":"sierra Calderona","slug":"sierra-calderona-en","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v21.9.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>sierra Calderona Archive - Lifestylehotels\u2122<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.lifestylehotels.net\/en\/tag\/sierra-calderona-en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"sierra Calderona Archive - Lifestylehotels\u2122\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.lifestylehotels.net\/en\/tag\/sierra-calderona-en\/\" \/>\n<meta property=\"og:site_name\" content=\"Lifestylehotels\u2122\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/www.lifestylehotels.net\/en\/tag\/sierra-calderona-en\/\",\"url\":\"https:\/\/www.lifestylehotels.net\/en\/tag\/sierra-calderona-en\/\",\"name\":\"sierra Calderona Archive - Lifestylehotels\u2122\",\"isPartOf\":{\"@id\":\"https:\/\/www.lifestylehotels.net\/de\/#website\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.lifestylehotels.net\/en\/tag\/sierra-calderona-en\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.lifestylehotels.net\/en\/tag\/sierra-calderona-en\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\/\/www.lifestylehotels.net\/en\/start-en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"sierra Calderona\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.lifestylehotels.net\/de\/#website\",\"url\":\"https:\/\/www.lifestylehotels.net\/de\/\",\"name\":\"Lifestylehotels\u2122\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.lifestylehotels.net\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"sierra Calderona Archive - Lifestylehotels\u2122","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lifestylehotels.net\/en\/tag\/sierra-calderona-en\/","og_locale":"en_US","og_type":"article","og_title":"sierra Calderona Archive - Lifestylehotels\u2122","og_url":"https:\/\/www.lifestylehotels.net\/en\/tag\/sierra-calderona-en\/","og_site_name":"Lifestylehotels\u2122","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.lifestylehotels.net\/en\/tag\/sierra-calderona-en\/","url":"https:\/\/www.lifestylehotels.net\/en\/tag\/sierra-calderona-en\/","name":"sierra Calderona Archive - Lifestylehotels\u2122","isPartOf":{"@id":"https:\/\/www.lifestylehotels.net\/de\/#website"},"breadcrumb":{"@id":"https:\/\/www.lifestylehotels.net\/en\/tag\/sierra-calderona-en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lifestylehotels.net\/en\/tag\/sierra-calderona-en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/www.lifestylehotels.net\/en\/start-en\/"},{"@type":"ListItem","position":2,"name":"sierra Calderona"}]},{"@type":"WebSite","@id":"https:\/\/www.lifestylehotels.net\/de\/#website","url":"https:\/\/www.lifestylehotels.net\/de\/","name":"Lifestylehotels\u2122","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lifestylehotels.net\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.lifestylehotels.net\/en\/wp-json\/wp\/v2\/tags\/5029"}],"collection":[{"href":"https:\/\/www.lifestylehotels.net\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.lifestylehotels.net\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.lifestylehotels.net\/en\/wp-json\/wp\/v2\/posts?tags=5029"},{"href":"https:\/\/www.lifestylehotels.net\/en\/wp-json\/wp\/v2\/stories?tags=5029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}